{"id":15372,"date":"2025-08-21T23:01:50","date_gmt":"2025-08-21T23:01:50","guid":{"rendered":"https:\/\/www.bookstream.shop\/product\/executive-book-summary-brian-tracy-discover-your-sales-strengths\/"},"modified":"2025-08-21T23:01:51","modified_gmt":"2025-08-21T23:01:51","slug":"executive-book-summary-brian-tracy-discover-your-sales-strengths","status":"publish","type":"product","link":"https:\/\/www.bookstream.shop\/en\/product\/executive-book-summary-brian-tracy-discover-your-sales-strengths\/","title":{"rendered":"Executive Book Summary Brian Tracy Discover Your Sales Strengths"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":15371,"template":"","meta":[],"product_brand":[],"product_cat":[129],"product_tag":[],"class_list":["post-15372","product","type-product","status-publish","has-post-thumbnail","product_cat-money-trading-finance","member-discount","discount-restricted","first","instock","downloadable","virtual","sold-individually","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/product\/15372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/product\/15372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/media\/15371"}],"wp:attachment":[{"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/media?parent=15372"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/product_brand?post=15372"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/product_cat?post=15372"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bookstream.shop\/en\/wp-json\/wp\/v2\/product_tag?post=15372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}